{"id":452,"date":"2022-06-29T11:14:27","date_gmt":"2022-06-29T09:14:27","guid":{"rendered":"https:\/\/www.medespoir-turquie.fr\/blog\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/"},"modified":"2022-06-29T11:14:27","modified_gmt":"2022-06-29T09:14:27","slug":"por-que-someterse-a-un-trasplante-capilar-en-turquia","status":"publish","type":"post","link":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/","title":{"rendered":"\u00bfPor qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda?"},"content":{"rendered":"<p>La <strong>ca\u00edda del cabello<\/strong> a una edad temprana es uno de los problemas m\u00e1s comunes a los que se enfrentan hombres y mujeres de todo el mundo. En consecuencia, esto ha llevado al desarrollo de diversos m\u00e9todos y t\u00e9cnicas para <em>restaurar el crecimiento del cabello<\/em>. En este sentido, el <strong>trasplante capilar <\/strong>se ha hecho muy popular como m\u00e9todo eficaz para tratar este problema. El m\u00e9todo de trasplante capilar se basa esencialmente en la extracci\u00f3n de unidades foliculares o FUE y <strong>Turqu\u00eda<\/strong> es uno de los primeros lugares donde se realiz\u00f3.<\/p>\n<h2>\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar?<\/h2>\n<p>En el campo de la cirug\u00eda est\u00e9tica, Turqu\u00eda es uno de los pa\u00edses m\u00e1s solicitados del mundo. Esta regi\u00f3n es un aut\u00e9ntico centro de turismo m\u00e9dico. Y entre las pr\u00e1cticas quir\u00fargicas m\u00e1s importantes se encuentra el trasplante capilar. Sin embargo, desde principios de la d\u00e9cada de 2000, Turqu\u00eda se ha convertido en el destino de la mayor\u00eda de los trasplantes capilares del mundo. De hecho, la formaci\u00f3n m\u00e9dica ha evolucionado mucho con el tiempo y hay m\u00e1s licenciados en medicina que en pa\u00edses como Estados Unidos, Francia, Grecia o Nueva Zelanda. Como resultado, se han construido muchos centros m\u00e9dicos en Turqu\u00eda, incluidos m\u00e1s de 500 centros de trasplante capilar s\u00f3lo en Estambul.<\/p>\n<p>La atracci\u00f3n que ejerce Turqu\u00eda por los trasplantes capilares genera un enorme \u00e9xito cada a\u00f1o. Prueba de ello es que una media de 180.000 personas acudieron all\u00ed para someterse a un trasplante capilar en 2019. Los pacientes proceden de Europa, Asia y \u00c1frica, pero tambi\u00e9n de Estados Unidos, Canad\u00e1, Brasil, Australia y Nueva Zelanda. Tal es la reputaci\u00f3n de los pocos pasajeros que no dudan en volar durante horas para someterse a una operaci\u00f3n que promete cambiarles la vida.<\/p>\n<h2>\u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?<\/h2>\n<p>Cabe preguntarse por qu\u00e9 es tan popular el <a href=\"https:\/\/www.medespoir-turquie.fr\/greffe-cheveux\">trasplante capilar turco<\/a>. Las cl\u00ednicas turcas de trasplante capilar ofrecen paquetes de trasplante capilar HID y FUE para todas las necesidades de los pacientes, y los paquetes est\u00e1ndar suelen incluir :<\/p>\n<ul>\n<li>Consulta con un especialista en trasplante capilar;<\/li>\n<li>An\u00e1lisis de sangre ;<\/li>\n<li>Fallo capilar DHI y FUE;<\/li>\n<li>Todos los medicamentos y consumibles ;<\/li>\n<li>Champ\u00fa ;<\/li>\n<li>Servicio de peluquer\u00eda ;<\/li>\n<li>Cuidados postoperatorios ;<\/li>\n<li>Alojamiento (normalmente en hotel) ;<\/li>\n<li>Transporte aeropuerto-cl\u00ednica-aeropuerto ;<\/li>\n<li>Asistencia ling\u00fc\u00edstica (int\u00e9rprete).<\/li>\n<\/ul>\n<h2>\u00bfY los beneficios?<\/h2>\n<p>Los precios del trasplante capilar en Turqu\u00eda son mucho m\u00e1s razonables que en casi cualquier otro pa\u00eds del mundo. Aunque los precios var\u00edan en funci\u00f3n de variables como el n\u00famero de trasplantes necesarios, el m\u00e9todo elegido, la cl\u00ednica y el cirujano, son muy asequibles en comparaci\u00f3n con los de otros pa\u00edses, pero con resultados similares, ya que esta diferencia se debe principalmente al coste de la vida en Turqu\u00eda.<\/p>\n<p>Adem\u00e1s del precio, hay otras ventajas, como<\/p>\n<h3>T\u00e9cnicas m\u00e1s avanzadas<\/h3>\n<p>En Turqu\u00eda, los cirujanos prefieren utilizar la t\u00e9cnica FUE (extracci\u00f3n de unidades foliculares), que provoca un dolor m\u00ednimo durante la recuperaci\u00f3n, no deja cicatrices visibles y el proceso de cicatrizaci\u00f3n es m\u00e1s r\u00e1pido. Adem\u00e1s, durante la operaci\u00f3n no se utiliza bistur\u00ed, grapas ni suturas. Mientras que el m\u00e9todo FUT (trasplante de unidades foliculares) requiere la extirpaci\u00f3n de la piel, en la t\u00e9cnica FUE las unidades foliculares se extraen individualmente de la zona donante del paciente y se trasplantan una a una en la zona de adelgazamiento.<\/p>\n<h3>Alta calidad en todos los aspectos<\/h3>\n<p>Debido a la feroz competencia del sector en Turqu\u00eda, las cl\u00ednicas mejoran continuamente sus m\u00e9todos, condiciones e instalaciones para ofrecer a sus pacientes el mejor servicio.<\/p>\n<h3>  Paquetes todo incluido<\/h3>\n<p>No hay mucho que decir sobre las instalaciones que ofrecen las cl\u00ednicas a trav\u00e9s de la competencia entre ellas. Ofrecen a sus pacientes transporte gratuito del aeropuerto al hotel, billetes de avi\u00f3n y alojamiento en buenos hoteles y mucho m\u00e1s, todo incluido en el coste final del trasplante capilar en Turqu\u00eda.<\/p>\n<h3>Lea tambi\u00e9n :<\/h3>\n<ol>\n<li><a href=\"https:\/\/www.medespoir-turquie.fr\/blog\/comment-choisir-son-hopital-pour-une-greffe-de-cheveux\/\">\u00bfC\u00f3mo elegir un hospital para un trasplante capilar?<\/a><\/li>\n<li><a href=\"\/blog?p=157\">\u00bfC\u00f3mo elegir entre FUE y HID?<\/a><\/li>\n<li><a href=\"https:\/\/www.medespoir-turquie.fr\/blog\/quel-prix-pour-des-implants-capillaires\/\">\u00bfCu\u00e1l es el precio de los implantes capilares?<\/a><\/li>\n<li><a href=\"https:\/\/www.medespoir-turquie.fr\/blog\/quand-ne-pas-faire-de-greffe-de-cheveux\/\">\u00bfCu\u00e1ndo no realizar un trasplante capilar?<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La ca\u00edda del cabello a una edad temprana es uno de los problemas m\u00e1s comunes a los que se enfrentan hombres y mujeres de todo el mundo. En consecuencia, esto ha llevado al desarrollo de diversos m\u00e9todos y t\u00e9cnicas para restaurar el crecimiento del cabello. En este sentido, el trasplante capilar se ha hecho muy [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda<\/title>\n<meta name=\"description\" content=\"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda\" \/>\n<meta property=\"og:description\" content=\"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog medespoir turkey es\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T09:14:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/06\/Pourquoi-aller-en-Turquie-pour-la-greffe-de-cheveux.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Huette Mo\u00efse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Huette Mo\u00efse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\"},\"author\":{\"name\":\"Huette Mo\u00efse\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\"},\"headline\":\"\u00bfPor qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda?\",\"datePublished\":\"2022-06-29T09:14:27+00:00\",\"dateModified\":\"2022-06-29T09:14:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\"},\"wordCount\":749,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization\"},\"articleSection\":[\"Belleza masculina\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\",\"name\":\"Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#website\"},\"datePublished\":\"2022-06-29T09:14:27+00:00\",\"dateModified\":\"2022-06-29T09:14:27+00:00\",\"description\":\"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?\",\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#website\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/\",\"name\":\"Blog medespoir turkey es\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization\",\"name\":\"Blog medespoir turkey es\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"contentUrl\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"width\":167,\"height\":64,\"caption\":\"Blog medespoir turkey es\"},\"image\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\",\"name\":\"Huette Mo\u00efse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"caption\":\"Huette Mo\u00efse\"},\"sameAs\":[\"https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda","description":"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda","og_description":"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?","og_url":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/","og_site_name":"Blog medespoir turkey es","article_published_time":"2022-06-29T09:14:27+00:00","og_image":[{"width":480,"height":256,"url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/06\/Pourquoi-aller-en-Turquie-pour-la-greffe-de-cheveux.jpg","type":"image\/jpeg"}],"author":"Huette Mo\u00efse","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Huette Mo\u00efse","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/#article","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/"},"author":{"name":"Huette Mo\u00efse","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07"},"headline":"\u00bfPor qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda?","datePublished":"2022-06-29T09:14:27+00:00","dateModified":"2022-06-29T09:14:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/"},"wordCount":749,"commentCount":0,"publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization"},"articleSection":["Belleza masculina"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/","name":"Por qu\u00e9 someterse a un trasplante capilar en Turqu\u00eda","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#website"},"datePublished":"2022-06-29T09:14:27+00:00","dateModified":"2022-06-29T09:14:27+00:00","description":"\u00bfPor qu\u00e9 Turqu\u00eda es un destino l\u00edder para el trasplante capilar? \u00bfQu\u00e9 ofrecen las cl\u00ednicas turcas de trasplante capilar?","inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir-turquie.fr\/blog\/es\/por-que-someterse-a-un-trasplante-capilar-en-turquia\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#website","url":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/","name":"Blog medespoir turkey es","description":"","publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#organization","name":"Blog medespoir turkey es","url":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","contentUrl":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","width":167,"height":64,"caption":"Blog medespoir turkey es"},"image":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07","name":"Huette Mo\u00efse","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","caption":"Huette Mo\u00efse"},"sameAs":["https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/posts\/452"}],"collection":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/comments?post=452"}],"version-history":[{"count":0,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/posts\/452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/media\/366"}],"wp:attachment":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/media?parent=452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/categories?post=452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/es\/wp-json\/wp\/v2\/tags?post=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}