{"id":183,"date":"2022-07-15T11:00:18","date_gmt":"2022-07-15T09:00:18","guid":{"rendered":"https:\/\/www.medespoir-turquie.fr\/blog\/?p=183"},"modified":"2022-07-15T11:12:34","modified_gmt":"2022-07-15T09:12:34","slug":"ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux","status":"publish","type":"post","link":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/","title":{"rendered":"Ces stars masculines qui ont eu une greffe de cheveux !"},"content":{"rendered":"<p>Tout comme les femmes, les hommes craignent la calvitie. C\u2019est ce qui explique d\u2019ailleurs la croissance du nombre des patients ayant eu recours \u00e0 des greffes capillaires pendant ces derni\u00e8res ann\u00e9es. Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont <a href=\"https:\/\/www.medespoir-turquie.fr\/greffe-cheveux\">subi une greffe de cheveux<\/a>.<\/p>\n<h2>La greffe de cheveux chez les hommes<\/h2>\n<p>Plusieurs \u00e9tudes scientifiques ont prouv\u00e9 que la chute de cheveux est la maladie du si\u00e8cle. Dans la plupart des cas, cette derni\u00e8re est caus\u00e9e par une mauvaise alimentation, stress, ou encore par une transmission h\u00e9r\u00e9ditaire. Soucieux de leur sant\u00e9 capillaire, les hommes aussi sont tent\u00e9s par les greffes de cheveux. Quels sont alors les stars qui ont subi ce traitement ?<\/p>\n<h3>Wayne Rooney<\/h3>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-184 aligncenter\" src=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Wayne-Rooney-greffe-cheveux-avant-apres-300x169.webp\" alt=\"Wayne Rooney greffe cheveux avant apres\" width=\"174\" height=\"98\" srcset=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Wayne-Rooney-greffe-cheveux-avant-apres-300x169.webp 300w, https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Wayne-Rooney-greffe-cheveux-avant-apres.webp 503w\" sizes=\"(max-width: 174px) 100vw, 174px\" \/><\/p>\n<p>L\u2019ex c\u00e9l\u00e8bre footballeur, Wayne Rooney est l\u2019une des stars masculines qui ont subi une transplantation capillaire. Actuellement, entra\u00eeneur de DC United, Rooney a publiquement parl\u00e9 de ses deux greffes de cheveux qu\u2019il a r\u00e9alis\u00e9es \u00e0 la clinique Harley Street de Londres.<\/p>\n<h3>Tom Hanks<\/h3>\n<p>Acteur, r\u00e9alisateur et producteur de cin\u00e9ma, Tom Hanks est l\u2019une des c\u00e9l\u00e9brit\u00e9s tant admir\u00e9es par les fans. Pour faire face \u00e0 la chute de cheveux, celui qui incarnait le r\u00f4le de Chuck Noland dans Seul au monde ait subi une greffe capillaire. Dans une toute r\u00e9cente interview, Tom Hanks a d\u00e9clar\u00e9 qu\u2019il est tr\u00e8s satisfait du r\u00e9sultat.<\/p>\n<h3>John Travolta<\/h3>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-185 aligncenter\" src=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres-300x198.webp\" alt=\"John Travolta greffe cheveux avant apres\" width=\"145\" height=\"96\" srcset=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres-300x198.webp 300w, https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres-768x508.webp 768w, https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres.webp 1024w\" sizes=\"(max-width: 145px) 100vw, 145px\" \/>Contrairement aux c\u00e9l\u00e9brit\u00e9s qui pr\u00e9f\u00e8rent ne rien cacher \u00e0 leurs fans, John Travolta n\u2019est jamais revenu sur sa nouvelle apparence physique. En effet, cet acteur iconique a bel et bien subi une greffe de cheveux. Sur la toile, des photos avant\/apr\u00e8s ont bien montr\u00e9 le changement<strong>.<\/strong><\/p>\n<h3>Ben Affleck<\/h3>\n<p>Contrairement \u00e0 ses camarades, Ben Affleck n\u2019a rien contre le fait de parler de sa greffe de cheveux. Interrog\u00e9 lors de plusieurs interviews sur cette solution capillaire, l\u2019acteur a bien confirm\u00e9 qu\u2019il s\u2019agit d\u2019un traitement miraculeux.<\/p>\n<h3>Jamie Foxx<\/h3>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-186 aligncenter\" src=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Jamie-Foxx-greffe-cheveux-avant-apres-300x169.jpg\" alt=\"Jamie Foxx greffe cheveux avant apres\" width=\"183\" height=\"103\" srcset=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Jamie-Foxx-greffe-cheveux-avant-apres-300x169.jpg 300w, https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Jamie-Foxx-greffe-cheveux-avant-apres-768x432.jpg 768w, https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/Jamie-Foxx-greffe-cheveux-avant-apres.jpg 1000w\" sizes=\"(max-width: 183px) 100vw, 183px\" \/>Jamie Foxx n\u2019a jamais parl\u00e9 de sa greffe de cheveux ! Cependant, ses d\u00e9tracteurs l\u2019ont fait. En effet, selon un grand nombre de ses haters, il semble que cet acteur a subi une greffe de cheveux en 2007. Et pour masquer la cicatrice de <a href=\"https:\/\/www.medespoir-turquie.fr\/blog\/comment-choisir-fue-ou-dhi\/\">FUT<\/a>.<\/p>\n<h3>Matthew McConaughey<\/h3>\n<p>Matthew McConaughey a fait l\u2019objet de plusieurs critiques s\u00e9v\u00e8res. En effet, dans plusieurs apparitions t\u00e9l\u00e9vis\u00e9es, Matthew a tendance \u00e0 nier le fait qu\u2019il a subi une transplantation capillaire. Pour se d\u00e9fendre, l\u2019acteur a affirm\u00e9 qu\u2019il utilise un m\u00e9dicament connu sous le nom de Regenix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout comme les femmes, les hommes craignent la calvitie. C\u2019est ce qui explique d\u2019ailleurs la croissance du nombre des patients ayant eu recours \u00e0 des greffes capillaires pendant ces derni\u00e8res ann\u00e9es. Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. La greffe de cheveux chez les hommes Plusieurs \u00e9tudes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Des stars masculines qui ont eu une greffe de cheveux !<\/title>\n<meta name=\"description\" content=\"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des stars masculines qui ont eu une greffe de cheveux !\" \/>\n<meta property=\"og:description\" content=\"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog medespoir turquie fr\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-15T09:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T09:12:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Huette Mo\u00efse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Huette Mo\u00efse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\"},\"author\":{\"name\":\"Huette Mo\u00efse\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\"},\"headline\":\"Ces stars masculines qui ont eu une greffe de cheveux !\",\"datePublished\":\"2022-07-15T09:00:18+00:00\",\"dateModified\":\"2022-07-15T09:12:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\"},\"articleSection\":[\"Beaut\u00e9 Homme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\",\"name\":\"Des stars masculines qui ont eu une greffe de cheveux !\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#website\"},\"datePublished\":\"2022-07-15T09:00:18+00:00\",\"dateModified\":\"2022-07-15T09:12:34+00:00\",\"description\":\"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#website\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/\",\"name\":\"Blog medespoir turquie fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.medespoir-turquie.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\",\"name\":\"Blog medespoir turquie fr\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"contentUrl\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"width\":167,\"height\":64,\"caption\":\"Blog medespoir turquie fr\"},\"image\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\",\"name\":\"Huette Mo\u00efse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"caption\":\"Huette Mo\u00efse\"},\"sameAs\":[\"https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des stars masculines qui ont eu une greffe de cheveux !","description":"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/","og_locale":"fr_FR","og_type":"article","og_title":"Des stars masculines qui ont eu une greffe de cheveux !","og_description":"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?","og_url":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/","og_site_name":"Blog medespoir turquie fr","article_published_time":"2022-07-15T09:00:18+00:00","article_modified_time":"2022-07-15T09:12:34+00:00","og_image":[{"width":1024,"height":677,"url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/07\/John-Travolta-greffe-cheveux-avant-apres.webp","type":"image\/webp"}],"author":"Huette Mo\u00efse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Huette Mo\u00efse","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/#article","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/"},"author":{"name":"Huette Mo\u00efse","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07"},"headline":"Ces stars masculines qui ont eu une greffe de cheveux !","datePublished":"2022-07-15T09:00:18+00:00","dateModified":"2022-07-15T09:12:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization"},"articleSection":["Beaut\u00e9 Homme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/","name":"Des stars masculines qui ont eu une greffe de cheveux !","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#website"},"datePublished":"2022-07-15T09:00:18+00:00","dateModified":"2022-07-15T09:12:34+00:00","description":"Sur la toile, plusieurs c\u00e9l\u00e9brit\u00e9s masculines ont d\u00e9clar\u00e9 qu\u2019ils ont subi une greffe de cheveux. Quels sont alors ?","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir-turquie.fr\/blog\/ces-stars-masculines-qui-ont-eu-une-greffe-de-cheveux\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#website","url":"https:\/\/www.medespoir-turquie.fr\/blog\/","name":"Blog medespoir turquie fr","description":"","publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir-turquie.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization","name":"Blog medespoir turquie fr","url":"https:\/\/www.medespoir-turquie.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","contentUrl":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","width":167,"height":64,"caption":"Blog medespoir turquie fr"},"image":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07","name":"Huette Mo\u00efse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","caption":"Huette Mo\u00efse"},"sameAs":["https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/183"}],"collection":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":5,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"predecessor-version":[{"id":191,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/183\/revisions\/191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/media\/185"}],"wp:attachment":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}