{"id":337,"date":"2022-12-21T11:30:16","date_gmt":"2022-12-21T10:30:16","guid":{"rendered":"https:\/\/www.medespoir-turquie.fr\/blog\/?p=337"},"modified":"2022-12-21T11:30:16","modified_gmt":"2022-12-21T10:30:16","slug":"virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage","status":"publish","type":"post","link":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/","title":{"rendered":"Chirurgie esth\u00e9tique : j\u2019ai fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !"},"content":{"rendered":"<p>\u00c0 l\u2019aube de la cinquantaine, <strong>Virginie<\/strong> a eu recours \u00e0 un <strong>lifting du visage<\/strong> pour <em>camoufler les marques de son op\u00e9ration rat\u00e9e<\/em> ! Cette patiente nous explique en d\u00e9tails comment la <strong>chirurgie esth\u00e9tique<\/strong> l\u2019a aid\u00e9 \u00e0 regagner confiance en elle.<\/p>\n<blockquote>\n<h2>J\u2019ai d\u00e9cid\u00e9 de sauter le pas de la chirurgie esth\u00e9tique<\/h2>\n<\/blockquote>\n<p>Ayant v\u00e9cu dans des climats tropicaux, Virginie avait tendance \u00e0 s&rsquo;exposer au soleil. \u00c0 l\u2019\u00e2ge de 45 ans, cette femme avait une peau affaiss\u00e9e. Tent\u00e9e par la chirurgie esth\u00e9tique, elle a donc d\u00e9cid\u00e9 de sauter le pas.<\/p>\n<blockquote><p>\u201c J&rsquo;ai commenc\u00e9 par l\u2019op\u00e9ration des paupi\u00e8res, aussi appel\u00e9e <a href=\"https:\/\/www.medespoir-turquie.fr\/blepharoplastie\">bl\u00e9pharoplastie<\/a>. Malheureusement, je n\u2019ai pas du tout \u00e9t\u00e9 satisfaite du r\u00e9sultat\u2026 J\u2019avais presque les paupi\u00e8res plus affaiss\u00e9es qu\u2019avant. J&rsquo;ai donc d\u00e9cid\u00e9 de consulter un autre chirurgien pour r\u00e9aliser une seconde bl\u00e9pharoplastie et un <a href=\"https:\/\/www.medespoir-turquie.fr\/blog\/johnny-depp-son-visage-transforme-par-la-chirurgie-esthetique\/\">lifting du visage<\/a> \u201d. Explique-t-elle.<\/p><\/blockquote>\n<p>Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage.<\/p>\n<h2>Quel est le r\u00e9sultat de ses op\u00e9rations esth\u00e9tiques ?<\/h2>\n<p>Ayant saut\u00e9 le pas pour la deuxi\u00e8me fois, Virginie a finalement obtenu le r\u00e9sultat souhait\u00e9. Satisfaite du travail de son nouveau chirurgien, elle a publiquement remerci\u00e9 son praticien nomm\u00e9, Dr Nguyen. \u201c Je conseille \u00e0 tout le monde de prendre diff\u00e9rents rendez-vous, de demander conseil, mais aussi de consulter les photos avant\/apr\u00e8s des sites internet des chirurgiens qui sont souvent un bon reflet de leur travail. Le Dr Nguyen correspondait parfaitement \u00e0 ce que je recherchais, je lui ai fait confiance et j\u2019ai d\u00e9cid\u00e9 de r\u00e9aliser tout d&rsquo;abord l&rsquo;op\u00e9ration des paupi\u00e8res, pour corriger ma bl\u00e9pharoplastie rat\u00e9e\u2026 L\u2019op\u00e9ration s\u2019est tr\u00e8s bien pass\u00e9e et nous avons pu ensuite parler de l\u2019op\u00e9ration du lifting.\u201d\u00a0 D\u00e9clare-t-elle.<\/p>\n<blockquote>\n<h2>J\u2019ai l\u2019impression d\u2019avoir rajeuni de 15 ans !<\/h2>\n<\/blockquote>\n<p>Apr\u00e8s deux mois de sa deuxi\u00e8me bl\u00e9pharoplastie, Virginie a r\u00e9alis\u00e9 un lifting de visage. Contrairement \u00e0 ce qu\u2019elle croyait, le r\u00e9sultat \u00e9tait tr\u00e8s naturel. Peau tonifi\u00e9e, visage rayonnant et bonne mine, ainsi \u00e9tait le rendu de ce traitement.<\/p>\n<blockquote><p>\u201c J\u2019ai l\u2019impression d\u2019avoir rajeuni de 15 ans ! Je me suis sentie tout de suite mieux dans ma peau. Je n\u2019ai plus cet affaissement de la peau qui me complexait, mais j\u2019ai surtout l\u2019air plus r\u00e9veill\u00e9e, plus en forme. C\u2019est tr\u00e8s naturel. D\u2019ailleurs, personne ne se doute que j\u2019ai fait un lifting, on me dit juste que j\u2019ai l\u2019air plus repos\u00e9e. C\u00f4t\u00e9 budget, j\u2019ai pay\u00e9 12 000 euros pour les deux op\u00e9rations \u201d. Explique-t-elle.<\/p><\/blockquote>\n<p>Virginie n\u2019a pas h\u00e9sit\u00e9 \u00e0 partager ses photos avant\/apr\u00e8s, sur les r\u00e9seaux sociaux. Plusieurs internautes ont \u00e9t\u00e9 surpris.<\/p>\n<blockquote><p>\u201cVoici des photos de moi deux mois apr\u00e8s l\u2019op\u00e9ration. On peut voir des petites cicatrices roses au niveau des oreilles, c&rsquo;est normal, elles deviennent ensuite compl\u00e8tement imperceptibles. Apr\u00e8s presque 1 an maintenant, je suis satisfaite du r\u00e9sultat. Mon visage para\u00eet plus jeune, mais aussi plus repos\u00e9, c&rsquo;est bluffant et en m\u00eame temps tr\u00e8s naturel\u2026 \u201c<\/p><\/blockquote>\n<p>Ainsi \u00e9tait l\u2019exp\u00e9rience de Virginie avec la chirurgie esth\u00e9tique. Ces deux op\u00e9rations esth\u00e9tiques l\u2019ont beaucoup aid\u00e9 \u00e0 \u00eatre en parfaite harmonie avec son corps.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019aube de la cinquantaine, Virginie a eu recours \u00e0 un lifting du visage pour camoufler les marques de son op\u00e9ration rat\u00e9e ! Cette patiente nous explique en d\u00e9tails comment la chirurgie esth\u00e9tique l\u2019a aid\u00e9 \u00e0 regagner confiance en elle. J\u2019ai d\u00e9cid\u00e9 de sauter le pas de la chirurgie esth\u00e9tique Ayant v\u00e9cu dans des climats [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !<\/title>\n<meta name=\"description\" content=\"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !\" \/>\n<meta property=\"og:description\" content=\"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog medespoir turquie fr\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T10:30:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/12\/Virginie-chirurgie-esthetique-blepharoplastie-et-lifting-de-visage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Huette Mo\u00efse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Huette Mo\u00efse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\"},\"author\":{\"name\":\"Huette Mo\u00efse\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\"},\"headline\":\"Chirurgie esth\u00e9tique : j\u2019ai fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !\",\"datePublished\":\"2022-12-21T10:30:16+00:00\",\"dateModified\":\"2022-12-21T10:30:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\"},\"wordCount\":599,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\"},\"articleSection\":[\"Beaut\u00e9 Stars\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\",\"name\":\"Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !\",\"isPartOf\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#website\"},\"datePublished\":\"2022-12-21T10:30:16+00:00\",\"dateModified\":\"2022-12-21T10:30:16+00:00\",\"description\":\"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#website\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/\",\"name\":\"Blog medespoir turquie fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.medespoir-turquie.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#organization\",\"name\":\"Blog medespoir turquie fr\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"contentUrl\":\"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png\",\"width\":167,\"height\":64,\"caption\":\"Blog medespoir turquie fr\"},\"image\":{\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07\",\"name\":\"Huette Mo\u00efse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g\",\"caption\":\"Huette Mo\u00efse\"},\"sameAs\":[\"https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !","description":"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/","og_locale":"fr_FR","og_type":"article","og_title":"Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !","og_description":"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage","og_url":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/","og_site_name":"Blog medespoir turquie fr","article_published_time":"2022-12-21T10:30:16+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/12\/Virginie-chirurgie-esthetique-blepharoplastie-et-lifting-de-visage.jpg","type":"image\/jpeg"}],"author":"Huette Mo\u00efse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Huette Mo\u00efse","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/#article","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/"},"author":{"name":"Huette Mo\u00efse","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07"},"headline":"Chirurgie esth\u00e9tique : j\u2019ai fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !","datePublished":"2022-12-21T10:30:16+00:00","dateModified":"2022-12-21T10:30:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/"},"wordCount":599,"commentCount":0,"publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization"},"articleSection":["Beaut\u00e9 Stars"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/","name":"Virginie fait un lifting du visage \u00e0 49 ans apr\u00e8s une op\u00e9ration rat\u00e9e !","isPartOf":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#website"},"datePublished":"2022-12-21T10:30:16+00:00","dateModified":"2022-12-21T10:30:16+00:00","description":"Bien qu\u2019elle a eu une mauvaise exp\u00e9rience suite \u00e0 son op\u00e9ration esth\u00e9tique rat\u00e9e, Virginie a d\u00e9cid\u00e9 de subir une deuxi\u00e8me bl\u00e9pharoplastie et un lifting de visage","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir-turquie.fr\/blog\/virginie-chirurgie-esthetique-blepharoplastie-lifting-de-visage\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#website","url":"https:\/\/www.medespoir-turquie.fr\/blog\/","name":"Blog medespoir turquie fr","description":"","publisher":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir-turquie.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#organization","name":"Blog medespoir turquie fr","url":"https:\/\/www.medespoir-turquie.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","contentUrl":"https:\/\/www.medespoir-turquie.fr\/blog\/web\/app\/uploads\/2022\/03\/logo-medespoir.png","width":167,"height":64,"caption":"Blog medespoir turquie fr"},"image":{"@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/bcd64adf2d25931f22588937255fec07","name":"Huette Mo\u00efse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir-turquie.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f10b17cd8969507f87270f327728d51?s=96&d=mm&r=g","caption":"Huette Mo\u00efse"},"sameAs":["https:\/\/medespoir-turquiefr.azurewebsites.net\/blog\/web\/wp"]}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/337"}],"collection":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/comments?post=337"}],"version-history":[{"count":1,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/337\/revisions"}],"predecessor-version":[{"id":339,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/posts\/337\/revisions\/339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/media\/338"}],"wp:attachment":[{"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/media?parent=337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/categories?post=337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir-turquie.fr\/blog\/wp-json\/wp\/v2\/tags?post=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}